{"id":1055,"date":"2021-01-20T18:25:20","date_gmt":"2021-01-20T21:25:20","guid":{"rendered":"http:\/\/dragoesdegaragem.com\/trabalhodemesa\/?p=1055"},"modified":"2021-03-23T20:12:53","modified_gmt":"2021-03-23T23:12:53","slug":"tdm-60-o-riso-parte-1","status":"publish","type":"post","link":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/","title":{"rendered":"TdM 60 &#8211; O Riso (parte 1)"},"content":{"rendered":"\r\n<p>O que \u00e9 o RISO, afinal? A plateia rir \u00e9 um sinal de que o espet\u00e1culo est\u00e1 indo bem? A com\u00e9dia quer o riso? Isso e muito mais nesse ep com participa\u00e7\u00e3o do <a href=\"https:\/\/twitter.com\/andrelt\" target=\"_blank\" rel=\"noopener\">@andrelt<\/a> <em>(Andr\u00e9 Thieme: Professor e Pesquisador. Analista do Comportamento. Psic\u00f3logo dos Drag\u00f5es de Garagem)<\/em> \u00a0<\/p>\r\n<p>Transcri\u00e7\u00e3o para Surdos: http:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2021\/03\/tdm60_o_riso.pdf\u00a0<\/p>\r\n\r\n\r\n\r\n<p><em>Tem interesse em anunciar no Trabalho de Mesa?\u00a0<\/em>Para nos achar:<\/p>\r\n\r\n\r\n\r\n<p><a href=\"https:\/\/www.facebook.com\/trabalhodemesa\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>\u00a0e\u00a0<a href=\"https:\/\/www.instagram.com\/trabalhodemesa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram\u00a0<\/a><\/p>\r\n\r\n\r\n\r\n<p>Entre em contato com o TdM:\u00a0<strong>bilheteria@trabalhodemesa.com<\/strong><\/p>\r\n\r\n\r\n\r\n<p><strong><em>Ficha T\u00e9cnica desse epis\u00f3dio:<\/em><\/strong><\/p>\r\n\r\n\r\n\r\n<p><em>Pauta: Reinecken<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>Apresentadores: Gustavo Reinecken, Ana Flavia Garcia, Andre Thieme e Hugo Leonardo<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>T\u00e9cnico de Grava\u00e7\u00e3o: Bruno Lagana<\/em>\u00a0<em>(<a href=\"https:\/\/www.instagram.com\/portalrefil\/\">@PortalRefil.)<\/a><\/em><\/p>\r\n\r\n\r\n\r\n<p><em>Editores:\u00a0<a href=\"https:\/\/www.instagram.com\/reinecken\/\" target=\"_blank\" rel=\"noreferrer noopener\">Reinecken<\/a>\u00a0\/\u00a0\u00a0<a href=\"https:\/\/soundcloud.com\/henrique_andrade\" target=\"_blank\" rel=\"noreferrer noopener\">Henrique Andrade<\/a><\/em><\/p>\r\n\r\n\r\n\r\n<p><em>Produ\u00e7\u00e3o Geral: Georgia Rafaela (Pratic\u00e1vel Produ\u00e7\u00e3o)<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>Produ\u00e7\u00e3o Executiva: Ana Paula Martins<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>Assessoria de Comunica\u00e7\u00e3o\/Divulga\u00e7\u00e3o:\u00a0<a href=\"https:\/\/www.instagram.com\/obregas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Daniel Obregon<\/a>\u00a0e Diego Matos\u00a0<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>Designer Gr\u00e1fico e Vitrine do TdM:\u00a0<a href=\"https:\/\/www.instagram.com\/obregas\/\">Daniel Obregon<\/a><\/em><\/p>\r\n\r\n\r\n\r\n<p><em>Dire\u00e7\u00e3o Geral: Reinecken<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>M\u00fasica tema do TdM: (Zypherum, da Banda Zoe).\u00a0<\/em><a href=\"https:\/\/www.instagram.com\/duosalimanga\/\">BC Araujo<\/a>\u00a0<em>(Guitarras, Viol\u00f5es e Viola); Beto Ramos (Pianos e Teclados);\u00a0<\/em><a href=\"https:\/\/www.instagram.com\/a.engrenagem\/\"><em>Pedro Miranda\u00a0<\/em><\/a><em>(Contra-Baixo ac\u00fastico); H\u00e9lio Miranda (Bateria).\u00a0Gravado no\u00a0<a href=\"https:\/\/www.youtube.com\/user\/confinsartisticos\">Est\u00fadio da E.T.C.A.<\/a>\u00a0por Reinecken e Miranda, Abril 2013, especialmente para a E.T.C.A. e o<\/em>\u00a0<em>Document\u00e1rio de\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=X9-NpFSVVPE\">LIBRAS PARA ARTE<\/a>.<\/em><\/p>\r\n\r\n\r\n\r\n<p>Autores e grava\u00e7\u00e3o das m\u00fasicas usadas no fundo desse epis\u00f3dio: Reinecken, BC, Roberto Ramos, Pedro Miranda, H\u00e9lio Miranda, &amp; Daniel Pitanga e Henrique Andrade<\/p>\r\n\r\n\r\n\r\n<p>As m\u00fasicas usadas no TdM s\u00e3o de autoria pr\u00f3pria! N\u00f3s incentivamos m\u00fasicos.<\/p>\r\n<p>CONHE\u00c7AM &#8211; https:\/\/henriqueandrade.net<\/p>\r\n<p>Entre em contato para novos neg\u00f3cios:<\/p>\r\n\r\n\r\n\r\n<p>Bilheteria@trabalhodemesa.com<\/p>\r\n\r\n\r\n\r\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-864\" src=\"http:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2019\/06\/Banner_FAC2019_Pre.png\" alt=\"\" width=\"1741\" height=\"262\" srcset=\"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2019\/06\/Banner_FAC2019_Pre.png 1741w, https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2019\/06\/Banner_FAC2019_Pre-300x45.png 300w, https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2019\/06\/Banner_FAC2019_Pre-768x116.png 768w, https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2019\/06\/Banner_FAC2019_Pre-1024x154.png 1024w, https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2019\/06\/Banner_FAC2019_Pre-1080x163.png 1080w\" sizes=\"auto, (max-width: 1741px) 100vw, 1741px\" \/><\/p>\r\n\r\n\r\n\r\n\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<p>Acesse:<\/p>\r\n\r\n\r\n\r\n<p><a href=\"https:\/\/www.patreon.com\/dragoesdegaragem\" target=\"_blank\" rel=\"noreferrer noopener\">patreon.com\/dragoesdegaragem\u00a0<\/a><\/p>\r\n\r\n\r\n","protected":false},"excerpt":{"rendered":"<p>O que \u00e9 o RISO, afinal? A plateia rir \u00e9 um sinal de que o espet\u00e1culo est\u00e1 indo bem? A com\u00e9dia quer o riso? Isso e muito mais nesse ep com participa\u00e7\u00e3o do @andrelt (Andr\u00e9 Thieme: Professor e Pesquisador. Analista do Comportamento. Psic\u00f3logo dos Drag\u00f5es de Garagem) \u00a0 Transcri\u00e7\u00e3o para Surdos: http:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2021\/03\/tdm60_o_riso.pdf\u00a0 Tem interesse em [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1058,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcast","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TdM 60 - O Riso (parte 1) - Trabalho de Mesa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TdM 60 - O Riso (parte 1) - Trabalho de Mesa\" \/>\n<meta property=\"og:description\" content=\"O que \u00e9 o RISO, afinal? A plateia rir \u00e9 um sinal de que o espet\u00e1culo est\u00e1 indo bem? A com\u00e9dia quer o riso? Isso e muito mais nesse ep com participa\u00e7\u00e3o do @andrelt (Andr\u00e9 Thieme: Professor e Pesquisador. Analista do Comportamento. Psic\u00f3logo dos Drag\u00f5es de Garagem) \u00a0 Transcri\u00e7\u00e3o para Surdos: http:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2021\/03\/tdm60_o_riso.pdf\u00a0 Tem interesse em [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Trabalho de Mesa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/trabalhodemesa\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-20T21:25:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-23T23:12:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2021\/01\/TdM60_Riso-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Reinecken\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TrabalhodeMesa\" \/>\n<meta name=\"twitter:site\" content=\"@TrabalhodeMesa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reinecken\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/tdm-60-o-riso-parte-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/tdm-60-o-riso-parte-1\\\/\"},\"author\":{\"name\":\"Reinecken\",\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/#\\\/schema\\\/person\\\/994ae127bc7add164ab3c5c5ad63e081\"},\"headline\":\"TdM 60 &#8211; O Riso (parte 1)\",\"datePublished\":\"2021-01-20T21:25:20+00:00\",\"dateModified\":\"2021-03-23T23:12:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/tdm-60-o-riso-parte-1\\\/\"},\"wordCount\":287,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/tdm-60-o-riso-parte-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/TdM60_Riso-2.png\",\"articleSection\":[\"Podcast\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/tdm-60-o-riso-parte-1\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/tdm-60-o-riso-parte-1\\\/\",\"url\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/tdm-60-o-riso-parte-1\\\/\",\"name\":\"TdM 60 - O Riso (parte 1) - Trabalho de Mesa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/tdm-60-o-riso-parte-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/tdm-60-o-riso-parte-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/TdM60_Riso-2.png\",\"datePublished\":\"2021-01-20T21:25:20+00:00\",\"dateModified\":\"2021-03-23T23:12:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/tdm-60-o-riso-parte-1\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/tdm-60-o-riso-parte-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/tdm-60-o-riso-parte-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/TdM60_Riso-2.png\",\"contentUrl\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/TdM60_Riso-2.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/tdm-60-o-riso-parte-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TdM 60 &#8211; O Riso (parte 1)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/#website\",\"url\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/\",\"name\":\"Trabalho de Mesa\",\"description\":\"Podcast sobre Teatro, Cinema, e Artes em Geral. Falamos da vida tamb\u00e9m!\",\"publisher\":{\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/#organization\",\"name\":\"Trabalho de Mesa - Podcas\",\"url\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/logo_TdM_cor-400.png\",\"contentUrl\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/logo_TdM_cor-400.png\",\"width\":400,\"height\":351,\"caption\":\"Trabalho de Mesa - Podcas\"},\"image\":{\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/trabalhodemesa\",\"https:\\\/\\\/x.com\\\/TrabalhodeMesa\",\"https:\\\/\\\/www.instagram.com\\\/trabalhodemesa\",\"https:\\\/\\\/www.youtube.com\\\/confinsartisticos\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/#\\\/schema\\\/person\\\/994ae127bc7add164ab3c5c5ad63e081\",\"name\":\"Reinecken\",\"sameAs\":[\"http:\\\/\\\/www.reinecken.me\",\"https:\\\/\\\/www.instagram.com\\\/reinecken\",\"linkedin.com\\\/in\\\/g-reinecken\"],\"url\":\"https:\\\/\\\/dragoesdegaragem.com\\\/trabalhodemesa\\\/author\\\/gustavo-reinecken\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TdM 60 - O Riso (parte 1) - Trabalho de Mesa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/","og_locale":"pt_BR","og_type":"article","og_title":"TdM 60 - O Riso (parte 1) - Trabalho de Mesa","og_description":"O que \u00e9 o RISO, afinal? A plateia rir \u00e9 um sinal de que o espet\u00e1culo est\u00e1 indo bem? A com\u00e9dia quer o riso? Isso e muito mais nesse ep com participa\u00e7\u00e3o do @andrelt (Andr\u00e9 Thieme: Professor e Pesquisador. Analista do Comportamento. Psic\u00f3logo dos Drag\u00f5es de Garagem) \u00a0 Transcri\u00e7\u00e3o para Surdos: http:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2021\/03\/tdm60_o_riso.pdf\u00a0 Tem interesse em [&hellip;]","og_url":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/","og_site_name":"Trabalho de Mesa","article_publisher":"https:\/\/www.facebook.com\/trabalhodemesa","article_published_time":"2021-01-20T21:25:20+00:00","article_modified_time":"2021-03-23T23:12:53+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2021\/01\/TdM60_Riso-2.png","type":"image\/png"}],"author":"Reinecken","twitter_card":"summary_large_image","twitter_creator":"@TrabalhodeMesa","twitter_site":"@TrabalhodeMesa","twitter_misc":{"Escrito por":"Reinecken","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/#article","isPartOf":{"@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/"},"author":{"name":"Reinecken","@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/#\/schema\/person\/994ae127bc7add164ab3c5c5ad63e081"},"headline":"TdM 60 &#8211; O Riso (parte 1)","datePublished":"2021-01-20T21:25:20+00:00","dateModified":"2021-03-23T23:12:53+00:00","mainEntityOfPage":{"@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/"},"wordCount":287,"commentCount":0,"publisher":{"@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/#organization"},"image":{"@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2021\/01\/TdM60_Riso-2.png","articleSection":["Podcast"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/","url":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/","name":"TdM 60 - O Riso (parte 1) - Trabalho de Mesa","isPartOf":{"@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/#primaryimage"},"image":{"@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2021\/01\/TdM60_Riso-2.png","datePublished":"2021-01-20T21:25:20+00:00","dateModified":"2021-03-23T23:12:53+00:00","breadcrumb":{"@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/#primaryimage","url":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2021\/01\/TdM60_Riso-2.png","contentUrl":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2021\/01\/TdM60_Riso-2.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/tdm-60-o-riso-parte-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/"},{"@type":"ListItem","position":2,"name":"TdM 60 &#8211; O Riso (parte 1)"}]},{"@type":"WebSite","@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/#website","url":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/","name":"Trabalho de Mesa","description":"Podcast sobre Teatro, Cinema, e Artes em Geral. Falamos da vida tamb\u00e9m!","publisher":{"@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/#organization","name":"Trabalho de Mesa - Podcas","url":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/#\/schema\/logo\/image\/","url":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2017\/01\/logo_TdM_cor-400.png","contentUrl":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-content\/uploads\/2017\/01\/logo_TdM_cor-400.png","width":400,"height":351,"caption":"Trabalho de Mesa - Podcas"},"image":{"@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/trabalhodemesa","https:\/\/x.com\/TrabalhodeMesa","https:\/\/www.instagram.com\/trabalhodemesa","https:\/\/www.youtube.com\/confinsartisticos"]},{"@type":"Person","@id":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/#\/schema\/person\/994ae127bc7add164ab3c5c5ad63e081","name":"Reinecken","sameAs":["http:\/\/www.reinecken.me","https:\/\/www.instagram.com\/reinecken","linkedin.com\/in\/g-reinecken"],"url":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/author\/gustavo-reinecken\/"}]}},"_links":{"self":[{"href":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-json\/wp\/v2\/posts\/1055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-json\/wp\/v2\/comments?post=1055"}],"version-history":[{"count":4,"href":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-json\/wp\/v2\/posts\/1055\/revisions"}],"predecessor-version":[{"id":1143,"href":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-json\/wp\/v2\/posts\/1055\/revisions\/1143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-json\/wp\/v2\/media\/1058"}],"wp:attachment":[{"href":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-json\/wp\/v2\/media?parent=1055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-json\/wp\/v2\/categories?post=1055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dragoesdegaragem.com\/trabalhodemesa\/wp-json\/wp\/v2\/tags?post=1055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}